{"id":33736,"date":"2024-11-20T01:23:35","date_gmt":"2024-11-20T06:23:35","guid":{"rendered":"https:\/\/bolttech.io\/news\/bolttech-et-hsbc-concluent-une-facilite-de-pret-damorcage-investissement-de-50-millions-de-dollars\/"},"modified":"2025-11-10T21:43:14","modified_gmt":"2025-11-10T13:43:14","slug":"bolttech-et-hsbc-concluent-une-facilite-de-pret-damorcage-investissement-de-50-millions-de-dollars","status":"publish","type":"post","link":"https:\/\/bolttech.io\/fr\/news\/bolttech-et-hsbc-concluent-une-facilite-de-pret-damorcage-investissement-de-50-millions-de-dollars\/","title":{"rendered":"bolttech et HSBC concluent une facilit\u00e9 de pr\u00eat d\u2019amor\u00e7age-investissement de 50 millions de dollars"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>bolttech<\/strong>, une entreprise mondiale d\u2019insurtech \u00e0 croissance rapide, a annonc\u00e9 aujourd\u2019hui la cl\u00f4ture d\u2019une facilit\u00e9 de cr\u00e9dit d\u2019amor\u00e7age-risque de 50 millions de dollars am\u00e9ricains avec HSBC. L\u2019installation soutiendra les futures initiatives de croissance strat\u00e9gique de bolttech, y compris l\u2019expansion du march\u00e9 et la recherche d\u2019opportunit\u00e9s pour renforcer ses capacit\u00e9s technologiques et de produits tout en am\u00e9liorant la flexibilit\u00e9 op\u00e9rationnelle. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Jonathan Yip, directeur g\u00e9n\u00e9ral, Services bancaires \u00e0 l\u2019innovation, HSBC<\/strong>, a d\u00e9clar\u00e9 : \u00ab Nous sommes heureux d\u2019offrir notre solution de pr\u00eat \u00e0 risque \u00e0 bolttech alors qu\u2019elle acc\u00e9l\u00e8re son parcours de croissance. La structure sur mesure des installations offre la flexibilit\u00e9 n\u00e9cessaire aux entreprises innovantes et \u00e0 forte croissance telles que bolttech pour capitaliser sur les tendances et les opportunit\u00e9s \u00e9mergentes.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Romaney O\u2019Malley, chef de la direction financi\u00e8re du groupe bolttech,<\/strong> a d\u00e9clar\u00e9 : \u00ab Avec HSBC, nous nous associons \u00e0 une banque mondiale de premier plan pour cr\u00e9er des occasions de financement strat\u00e9gique qui soutiendront notre croissance, tout en \u00e9largissant notre partenariat bancaire existant. Cette facilit\u00e9 t\u00e9moigne de la confiance de la HSBC dans la vision et la trajectoire de croissance de bolttech, ce qui marque un partenariat qui g\u00e9n\u00e9rera de la valeur mutuelle.<\/p>\n\n<p class=\"wp-block-paragraph\">En tant que partenaire bancaire cl\u00e9 de bolttech, HSBC soutient le parcours de croissance de l\u2019entreprise depuis 2019, en fournissant une large gamme de services bancaires et de financement dans l\u2019ensemble de ses activit\u00e9s dans plus de 14 pays.<\/p>\n\n<p class=\"wp-block-paragraph\">La facilit\u00e9 de cr\u00e9dit pluriannuelle sur mesure est structur\u00e9e de mani\u00e8re \u00e0 offrir une utilisation flexible, ce qui permet \u00e0 bolttech de capitaliser davantage sur le march\u00e9 mondial de l\u2019assurance int\u00e9gr\u00e9e, en pleine croissance. La HSBC est le seul pr\u00eateur pour l\u2019op\u00e9ration. <\/p>\n\n<p class=\"wp-block-paragraph\">La HSBC offre des solutions de financement strat\u00e9giques, des services bancaires et du soutien-conseil aux entreprises \u00e9mergentes dans des secteurs de la nouvelle \u00e9conomie, comme la technologie et les sciences de la vie. Depuis mai 2023, la Banque a \u00e9galement introduit le pr\u00eat \u00e0 risque comme outil compl\u00e9mentaire pour les entreprises en phase de croissance soutenues par des investisseurs dans l\u2019\u00e9conomie de l\u2019innovation. <\/p>\n\n<p class=\"wp-block-paragraph\">FIN<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de bolttech  <\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Bolttech est une insurtech mondiale dont la mission est de cr\u00e9er le premier \u00e9cosyst\u00e8me technologique mondial de protection et d\u2019assurance. bolttech sert des clients dans plus de 35 march\u00e9s en Am\u00e9rique du Nord, en Asie, en Europe et en Afrique.  Gr\u00e2ce \u00e0 une gamme compl\u00e8te de capacit\u00e9s num\u00e9riques et ax\u00e9es sur les donn\u00e9es, bolttech alimente les connexions entre les assureurs, les distributeurs et les clients pour faciliter et rendre plus efficace l\u2019achat et la vente de produits d\u2019assurance et de protection.  <\/p>\n\n<p class=\"wp-block-paragraph\">Pour plus d\u2019informations, veuillez consulter le site : <a href=\"http:\/\/www.bolttech.io\">www.bolttech.io<\/a>.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de The Hongkong and Shanghai Banking Corporation Limited<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">  La Hongkong and Shanghai Banking Corporation Limited est le membre fondateur du Groupe HSBC. La HSBC sert des clients dans le monde entier \u00e0 partir de bureaux situ\u00e9s dans 60 pays et territoires. Avec des actifs de 3 099 milliards de dollars am\u00e9ricains au 30 septembre 2024, HSBC est l\u2019une des plus grandes organisations de services bancaires et financiers au monde.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Pour les demandes des m\u00e9dias, veuillez contacter :<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">FTI Consulting <a href=\"mailto:bolttech@fticonsulting.com\">bolttech@fticonsulting.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>bolttech, une entreprise mondiale d\u2019insurtech \u00e0 croissance rapide, a annonc\u00e9 aujourd\u2019hui la cl\u00f4ture d\u2019une facilit\u00e9 de cr\u00e9dit d\u2019amor\u00e7age-risque de 50 millions de dollars am\u00e9ricains avec HSBC. L\u2019installation soutiendra les futures initiatives de croissance strat\u00e9gique de bolttech, y compris l\u2019expansion du march\u00e9 et la recherche d\u2019opportunit\u00e9s pour renforcer ses capacit\u00e9s technologiques et de produits tout en [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[55],"class_list":["post-33736","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"acf":[],"_links":{"self":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/posts\/33736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/comments?post=33736"}],"version-history":[{"count":0,"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/posts\/33736\/revisions"}],"wp:attachment":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/media?parent=33736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/categories?post=33736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}