{"id":21113,"date":"2024-09-30T14:21:45","date_gmt":"2024-09-30T19:21:45","guid":{"rendered":"https:\/\/bolttech.io\/insights\/assurance-cybersecurite-repondre-aux-risques-et-aux-preoccupations-a-lere-numerique\/"},"modified":"2024-09-30T14:21:51","modified_gmt":"2024-09-30T19:21:51","slug":"assurance-cybersecurite-repondre-aux-risques-et-aux-preoccupations-a-lere-numerique","status":"publish","type":"insight","link":"https:\/\/bolttech.io\/fr\/insights\/assurance-cybersecurite-repondre-aux-risques-et-aux-preoccupations-a-lere-numerique\/","title":{"rendered":"Assurance cybers\u00e9curit\u00e9 : r\u00e9pondre aux risques et aux pr\u00e9occupations \u00e0 l\u2019\u00e8re num\u00e9rique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La cybercriminalit\u00e9 co\u00fbte 600 milliards de dollars par an aux entreprises et aux particuliers, selon <a href=\"https:\/\/www.propertycasualty360.com\/2018\/05\/02\/the-future-of-cyber-claims\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mike Taylor<\/a> de PropertyCasualty360.\nPar cons\u00e9quent, de nombreux clients d\u2019assurance cherchent \u00e0 obtenir une couverture pour leurs pertes par le biais d\u2019une assurance sp\u00e9cialis\u00e9e en mati\u00e8re de biens ou de responsabilit\u00e9 civile. <\/p>\n\n<p class=\"wp-block-paragraph\">Connue sous le nom d\u2019assurance cyber, d\u2019assurance cybers\u00e9curit\u00e9 ou d\u2019assurance cyberresponsabilit\u00e9, cette couverture se concentre sur l\u2019atteinte, la perte ou l\u2019endommagement de donn\u00e9es num\u00e9riques et d\u2019actifs similaires.\nBien que la cyberassurance reste principalement un produit commercial, les polices personnelles suscitent de plus en plus d\u2019int\u00e9r\u00eat parmi les personnes qui cherchent \u00e9galement \u00e0 prot\u00e9ger leurs propres donn\u00e9es, explique M. Taylor. <\/p>\n\n<p class=\"wp-block-paragraph\">Les assureurs qui comprennent ce nouveau monde de risques peuvent offrir une couverture plus efficace tout en augmentant la fid\u00e9lit\u00e9 et la confiance des clients.<\/p>\n\n<h2 class=\"wp-block-heading\">Qu\u2019est-ce que l\u2019assurance cybers\u00e9curit\u00e9 ?<\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019assurance cybers\u00e9curit\u00e9 prot\u00e8ge les personnes et leurs informations contre les menaces en ligne, explique <a href=\"https:\/\/blog.commonwealth.com\/breaking-it-down-cyber-liability-insurance-and-common-misconceptions\" target=\"_blank\" rel=\"noreferrer noopener\">Rachel Sonia<\/a> de Commonwealth Independent Advisor.\n\u00ab L\u2019assurance cyberresponsabilit\u00e9 aide \u00e0 att\u00e9nuer l\u2019exposition aux risques en compensant les co\u00fbts li\u00e9s \u00e0 la r\u00e9cup\u00e9ration apr\u00e8s une attaque ou une atteinte \u00e0 la cybers\u00e9curit\u00e9 \u00bb.\nIl peut prot\u00e9ger un titulaire de police contre les pertes de premi\u00e8re partie, les r\u00e9clamations de tiers ou les deux.  <\/p>\n\n<p class=\"wp-block-paragraph\">L\u2019assurance cyberresponsabilit\u00e9 civile de premi\u00e8re partie couvre le co\u00fbt des atteintes au r\u00e9seau de l\u2019assur\u00e9, comme les notifications aux clients, les enqu\u00eates sur l\u2019atteinte et la protection antifraude.\nLa couverture des tiers fournit un soutien aux titulaires de police au cas o\u00f9 ils seraient poursuivis ou tenus responsables d\u2019une violation de donn\u00e9es. <\/p>\n\n<p class=\"wp-block-paragraph\">\u00c9tant donn\u00e9 que la cyberassurance reste un nouveau domaine de couverture, les d\u00e9tails de l\u2019\u00e9valuation des risques sont encore en cours de formulation par les compagnies d\u2019assurance.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab Bien que les assureurs automobiles puissent extraire des donn\u00e9es fiables des bo\u00eetes noires pour cartographier le comportement des conducteurs et d\u00e9couvrir les risques, ce n\u2019est pas si facile avec la cybers\u00e9curit\u00e9. Les assureurs ont besoin de mesures pour les aider \u00e0 faire la distinction entre les candidats \u00e0 haut risque et les candidats \u00e0 faible risque \u00bb, explique <a href=\"https:\/\/www.propertycasualty360.com\/2018\/05\/25\/can-behavior-based-cyber-insurance-improve-cyberse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jack Kudale<\/a>, ancien directeur de l\u2019exploitation de Cavirin Systems et actuel fondateur et PDG de la plateforme de cyberassurance Cowbell.<\/p>\n\n<p class=\"wp-block-paragraph\">Les compagnies d\u2019assurance qui consacrent des ressources \u00e0 l\u2019\u00e9laboration de ces mesures d\u00e8s maintenant peuvent acc\u00e9der plus rapidement au march\u00e9 des couvertures.\nEt ce march\u00e9 est plus vaste qu\u2019il n\u2019y para\u00eet \u00e0 premi\u00e8re vue. <\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab Ce n\u2019est pas seulement une question d\u2019informatique, ce n\u2019est pas seulement une affaire d\u2019entreprise technologique. C\u2019est tout le monde \u00bb, a d\u00e9clar\u00e9 <a href=\"https:\/\/www.axios.com\/cybersecurity-insurance-on-rise-companies-c2d2167e-9425-418e-bef9-6dfbc141deba.html\" target=\"_blank\" rel=\"noreferrer noopener\">Jason Hogg<\/a>, chef de la direction de Cyber Solutions chez Aon.\nLe besoin pressant d\u2019une couverture de cyberresponsabilit\u00e9 pr\u00e9sente des opportunit\u00e9s cl\u00e9s pour les assureurs de dommages. <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics-1024x683.jpg\" alt=\"\" class=\"wp-image-6123\" srcset=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics-1024x683.jpg 1024w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics-300x200.jpg 300w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics-768x512.jpg 768w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics-1536x1024.jpg 1536w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/data-analytics.jpg 1999w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Les risques de cybers\u00e9curit\u00e9 et leur couverture<\/h2>\n\n<p class=\"wp-block-paragraph\">L\u2019assurance cybers\u00e9curit\u00e9 est relativement nouvelle pour les clients et les assureurs.\nDe nombreuses entreprises n\u2019ont pas de polices qui r\u00e9pondent aux besoins sp\u00e9cifiques de l\u2019industrie, \u00e9crit <a href=\"https:\/\/www.propertycasualty360.com\/2018\/07\/10\/cybersecurity-insurance-popular-but-poorly-underst\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eleanor Vaida Gerhards<\/a> , associ\u00e9e de Fox Rothschild, sur PropertyCasualty360. <\/p>\n\n<p class=\"wp-block-paragraph\">\u00ab Pour \u00e9viter les lacunes et les litiges potentiels en mati\u00e8re de couverture, les courtiers et les assureurs devraient travailler en \u00e9troite collaboration avec les clients afin d\u2019identifier leurs risques uniques, d\u2019adapter la couverture pour y faire face et de s\u2019assurer que leurs assur\u00e9s savent exactement ce qui est couvert et ce qui ne l\u2019est pas \u00bb, \u00e9crit M. Gerhards.<\/p>\n\n<p class=\"wp-block-paragraph\">D\u2019autres clients supposent que leur police d\u2019assurance responsabilit\u00e9 civile g\u00e9n\u00e9rale couvrira une violation de donn\u00e9es.\nSouvent, ce n\u2019est pas le cas : la couverture de responsabilit\u00e9 civile g\u00e9n\u00e9rale d\u2019un titulaire de police peut ne pas compenser ad\u00e9quatement les pertes caus\u00e9es par le piratage ou d\u2019autres probl\u00e8mes de donn\u00e9es, explique <a href=\"http:\/\/www.orrm.com\/blog\/cyber-liability-and-gl-policies\" target=\"_blank\" rel=\"noreferrer noopener\">Wendy Marx<\/a> de Old Republic Risk Management. <\/p>\n\n<p class=\"wp-block-paragraph\">Pour d\u00e9terminer si une police d\u2019assurance responsabilit\u00e9 civile g\u00e9n\u00e9rale couvre les pertes li\u00e9es aux cyberrisques, les assureurs et les titulaires de police peuvent \u00eatre contraints de se tourner vers les tribunaux.\nPar exemple, plusieurs tribunaux, dont la Cour d\u2019appel du quatri\u00e8me circuit et la Cour d\u2019appel du Texas, ont conclu que les pertes d\u2019un assur\u00e9 r\u00e9sultant d\u2019une violation de donn\u00e9es \u00e9taient couvertes par des polices d\u2019assurance responsabilit\u00e9 civile civile civile des biens.\nCes plans contenaient d\u00e9j\u00e0 un langage sp\u00e9cifique d\u00e9finissant les donn\u00e9es \u00e9lectroniques comme une forme de propri\u00e9t\u00e9, disent <a href=\"https:\/\/www.propertycasualty360.com\/2018\/03\/09\/whats-the-best-business-insurance-to-cover-a-cyber\/\" target=\"_blank\" rel=\"noreferrer noopener\">Eric B. Stern et Andrew A. Lipkowitz<\/a>, associ\u00e9s chez Kaufman Dolowich &amp; Voluck LLP.  <\/p>\n\n<p class=\"wp-block-paragraph\">Si une police d\u2019assurance responsabilit\u00e9 civile g\u00e9n\u00e9rale mentionne sp\u00e9cifiquement les violations de donn\u00e9es, une police d\u2019assurance cyberresponsabilit\u00e9 distincte peut non seulement \u00eatre superflue, mais aussi cr\u00e9er un risque de garanties contradictoires qui co\u00fbtent plus de temps et d\u2019efforts \u00e0 trier.\nCe risque est accru lorsqu\u2019un client souscrit une assurance cyberresponsabilit\u00e9 aupr\u00e8s d\u2019un assureur alors qu\u2019il d\u00e9tient d\u00e9j\u00e0 une assurance habitation ou une assurance g\u00e9n\u00e9rale aupr\u00e8s d\u2019un autre assureur. <\/p>\n\n<p class=\"wp-block-paragraph\">Une fois qu\u2019une violation se produit, la plupart des assur\u00e9s savent que la prochaine \u00e9tape consiste \u00e0 d\u00e9poser une r\u00e9clamation.\nCependant, comme les violations de donn\u00e9es et l\u2019assurance cyber-responsabilit\u00e9 sont encore relativement nouvelles, de nombreux clients et compagnies d\u2019assurance ne comprennent pas clairement les pi\u00e8ges potentiels du processus de r\u00e9clamation, explique <a href=\"https:\/\/www.propertycasualty360.com\/2017\/06\/22\/cyber-insurance-claims-what-happens-when-a-breach\/\" target=\"_blank\" rel=\"noreferrer noopener\">David T. Vanalek<\/a>, directeur de l\u2019exploitation des r\u00e9clamations chez Markel. <\/p>\n\n<p class=\"wp-block-paragraph\">Par exemple, la n\u00e9cessit\u00e9 d\u2019\u00e9tablir des protocoles de confidentialit\u00e9 entourant l\u2019atteinte elle-m\u00eame et les donn\u00e9es compromises peut poser des d\u00e9fis.\nContrairement \u00e0 un accident de voiture ordinaire ou \u00e0 un incendie de maison, les dommages caus\u00e9s par une violation de donn\u00e9es peuvent \u00eatre irr\u00e9vocablement aggrav\u00e9s par les assureurs qui ne maintiennent pas de protocoles de s\u00e9curit\u00e9 stricts lorsqu\u2019ils r\u00e9pondent \u00e0 la r\u00e9clamation d\u00e9pos\u00e9e. <\/p>\n\n<p class=\"wp-block-paragraph\">De plus, comme la cyberresponsabilit\u00e9 peut \u00eatre couverte par plus d\u2019une police, la n\u00e9cessit\u00e9 de rester vigilant face aux r\u00e9clamations de tiers reste \u00e9lev\u00e9e.\nLes assureurs peuvent avoir besoin de coordonner non seulement les r\u00e9clamations de leurs propres assur\u00e9s, mais aussi celles de tiers comme les soci\u00e9t\u00e9s de cartes de cr\u00e9dit ou les clients de leurs assur\u00e9s. <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"616\" src=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech-1024x616.jpg\" alt=\"\" class=\"wp-image-6133\" srcset=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech-1024x616.jpg 1024w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech-300x180.jpg 300w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech-768x462.jpg 768w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech-1536x924.jpg 1536w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/tech.jpg 1999w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Avantages d\u2019offrir une couverture de cybers\u00e9curit\u00e9<\/h2>\n\n<p class=\"wp-block-paragraph\">En plus d\u2019attirer de nouveaux clients avec des produits sur mesure, les compagnies d\u2019assurance peuvent g\u00e9n\u00e9rer et profiter d\u2019un certain nombre d\u2019avantages plus larges en offrant une couverture de cyberresponsabilit\u00e9.<\/p>\n\n<p class=\"wp-block-paragraph\">L\u2019assurance cyberresponsabilit\u00e9 demeure faible, mais la demande croissante cr\u00e9e un march\u00e9 inexploit\u00e9 pour les nouveaux clients de l\u2019assurance de dommages.\nL\u2019\u00e9tude sur le <a href=\"https:\/\/www.ciab.com\/resources\/cyber-market-survey-spring-2017\/\" target=\"_blank\" rel=\"noreferrer noopener\">cybermarch\u00e9 de 2017<\/a> du Council of Insurance Agents and Brokers (CIAB) a r\u00e9v\u00e9l\u00e9 que seulement 32 % des clients d\u2019assurance avaient souscrit une assurance cyberresponsabilit\u00e9 ou une couverture contre les atteintes \u00e0 la protection des donn\u00e9es.\nCependant, le sondage de 2018 a r\u00e9v\u00e9l\u00e9 que 79 % des compagnies d\u2019assurance ont d\u00e9clar\u00e9 avoir constat\u00e9 une augmentation de la demande pour cette couverture, explique <a href=\"https:\/\/www.ciab.com\/resources\/q1-p-c-market-survey-2018\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rob Boyce<\/a> du CIAB.  <\/p>\n\n<p class=\"wp-block-paragraph\">Le march\u00e9 potentiel pour les clients d\u2019assurance cybers\u00e9curit\u00e9 s\u2019\u00e9tend bien au-del\u00e0 des marques nationales et internationales dont les r\u00e9centes violations de donn\u00e9es ont fait les gros titres.\n\u00ab Pour les petites entreprises, rien n\u2019est plus important que de prot\u00e9ger leur gagne-pain. L\u2019assurance cyberresponsabilit\u00e9 est un autre outil qu\u2019ils peuvent utiliser pour pr\u00e9venir un d\u00e9sastre financier en cas d\u2019attaque malveillante \u00bb, explique <a href=\"https:\/\/www.hiscox.com\/blog\/why-buy-cyber-liability-insurance-your-small-business\" target=\"_blank\" rel=\"noreferrer noopener\">Natalie Cooper<\/a>, r\u00e9dactrice en chef de BankingSense.com. <\/p>\n\n<p class=\"wp-block-paragraph\">Toute entreprise qui traite des donn\u00e9es personnelles de clients a besoin de mesures de s\u00e9curit\u00e9 et d\u2019une couverture en cas de violation, d\u00e9clare <a href=\"https:\/\/www.thedoctors.com\/articles\/cybersecurity-insurance-for-medical-practices-the-basics\/\" target=\"_blank\" rel=\"noreferrer noopener\">David J. Eismont<\/a> de The Doctors Company.\nLes banques, les compagnies d\u2019assurance et les cabinets m\u00e9dicaux en donnent des exemples \u00e9vidents, mais le besoin de protection s\u2019\u00e9tend \u00e0 l\u2019ensemble du monde des affaires, des plus grandes banques aux plus petits d\u00e9panneurs qui traitent les cartes de cr\u00e9dit ou d\u2019autres informations sur les clients. <\/p>\n\n<p class=\"wp-block-paragraph\">Les assureurs qui accordent la priorit\u00e9 \u00e0 la compr\u00e9hension et \u00e0 l\u2019offre d\u2019une couverture de cyberresponsabilit\u00e9 ont donc l\u2019occasion d\u2019exploiter un nouveau march\u00e9 important, d\u2019accro\u00eetre leurs r\u00e9sultats et d\u2019aider l\u2019entreprise \u00e0 atteindre ses objectifs de croissance et de rendement.<\/p>\n\n<p class=\"wp-block-paragraph\">La pr\u00e9sence d\u2019une couverture de cyberresponsabilit\u00e9 elle-m\u00eame peut \u00e9galement contribuer \u00e0 r\u00e9duire le risque de violation de donn\u00e9es en fa\u00e7onnant le comportement des assur\u00e9s.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00c9tant donn\u00e9 que les violations de donn\u00e9es sont encore une menace relativement nouvelle et que leur co\u00fbt peut sembler intangible, de nombreuses entreprises tardent \u00e0 adopter de nouvelles technologies et de nouveaux processus capables de pr\u00e9venir les violations de donn\u00e9es.\nCes outils et processus peuvent \u00eatre co\u00fbteux, et les entreprises peuvent ne pas voir leur valeur tant qu\u2019une violation ne s\u2019est pas d\u00e9j\u00e0 produite, expliquent <a href=\"https:\/\/assets.kpmg\/content\/dam\/kpmg\/xx\/pdf\/2017\/07\/cyber-insurance-report.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Paul Merrey<\/a> et ses coll\u00e8gues chercheurs de KPMG International. <\/p>\n\n<p class=\"wp-block-paragraph\">Cependant, les entreprises qui sont tenues de respecter certaines normes dans le cadre de leurs polices d\u2019assurance cyber sont plus susceptibles de comprendre la n\u00e9cessit\u00e9 de la s\u00e9curit\u00e9 des donn\u00e9es et d\u2019en tirer parti pour leur entreprise.\nIls sont \u00e9galement plus susceptibles d\u2019adopter ces outils une fois qu\u2019ils comprennent quels risques existent et comment leur assurance les aborde. <\/p>\n\n<p class=\"wp-block-paragraph\">Alors que la s\u00e9curit\u00e9 des donn\u00e9es reste une pr\u00e9occupation majeure pour les entreprises du monde entier, les compagnies d\u2019assurance ont la possibilit\u00e9 d\u2019am\u00e9liorer la s\u00e9curit\u00e9, d\u2019att\u00e9nuer les risques et d\u2019exploiter une nouvelle client\u00e8le.\nLes assureurs peuvent atteindre ces objectifs en comprenant les cyberrisques et en fournissant aux titulaires de police d\u2019assurance cybers\u00e9curit\u00e9 les \u00e9l\u00e9ments dont ils ont besoin pour se prot\u00e9ger et prot\u00e9ger leurs propres clients. <\/p>\n\n<p class=\"wp-block-paragraph\"><em>Images par\u00a0: everythingpossible\/\u00a9123RF.com, Konstantin Pelikh\/\u00a9123RF.com, everythingpossible\/\u00a9123RF.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La cybercriminalit\u00e9 co\u00fbte 600 milliards de dollars par an aux entreprises et aux particuliers, selon Mike Taylor de PropertyCasualty360. Par cons\u00e9quent, de nombreux clients d\u2019assurance cherchent \u00e0 obtenir une couverture pour leurs pertes par le biais d\u2019une assurance sp\u00e9cialis\u00e9e en mati\u00e8re de biens ou de responsabilit\u00e9 civile. Connue sous le nom d\u2019assurance cyber, d\u2019assurance cybers\u00e9curit\u00e9 [&hellip;]<\/p>\n","protected":false},"featured_media":0,"template":"","insight-category":[],"class_list":["post-21113","insight","type-insight","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/insight\/21113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/insight"}],"about":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/types\/insight"}],"wp:attachment":[{"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/media?parent=21113"}],"wp:term":[{"taxonomy":"insight-category","embeddable":true,"href":"https:\/\/bolttech.io\/fr\/wp-json\/wp\/v2\/insight-category?post=21113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}