{"id":44583,"date":"2019-11-20T00:12:00","date_gmt":"2019-11-19T16:12:00","guid":{"rendered":"https:\/\/bolttech.io\/insights\/cambio-operativo-por-que-las-aseguradoras-de-seguros-generales-necesitan-empleados-con-conocimientos-digitales\/"},"modified":"2025-09-09T01:53:21","modified_gmt":"2025-09-08T17:53:21","slug":"cambio-operativo-por-que-las-aseguradoras-de-seguros-generales-necesitan-empleados-con-conocimientos-digitales","status":"publish","type":"insight","link":"https:\/\/bolttech.io\/es\/insights\/cambio-operativo-por-que-las-aseguradoras-de-seguros-generales-necesitan-empleados-con-conocimientos-digitales\/","title":{"rendered":"Cambio operativo: por qu\u00e9 las aseguradoras de seguros generales necesitan empleados con conocimientos digitales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La transformaci\u00f3n digital est\u00e1 arrasando con los seguros. Los nuevos m\u00e9todos para garantizar la seguridad, el procesamiento m\u00e1s r\u00e1pido de los reclamos, la personalizaci\u00f3n de las ofertas de seguros y una mayor transparencia han sido el resultado de un movimiento hacia un futuro digital. <\/p>\n\n<p class=\"wp-block-paragraph\">Las tecnolog\u00edas y plataformas digitales brindan nuevas oportunidades para la innovaci\u00f3n en seguros e industrias relacionadas. Por ejemplo, muchas compa\u00f1\u00edas de seguros han adoptado la innovaci\u00f3n en forma de veh\u00edculos aut\u00f3nomos y dispositivos dom\u00e9sticos conectados como termostatos y sensores de humedad, dice <a href=\"https:\/\/www.propertycasualty360.com\/2018\/12\/17\/how-insurers-are-prioritizing-digital-transformati\/\" target=\"_blank\" rel=\"noreferrer noopener\">Toni Tomic<\/a>, jefe de seguros IBU en SAP. <\/p>\n\n<p class=\"wp-block-paragraph\">La innovaci\u00f3n tambi\u00e9n es esencial dentro de las compa\u00f1\u00edas de seguros. Es particularmente vital para las aseguradoras tradicionales, que enfrentan una nueva competencia de nuevas empresas de insurtech y otros competidores, dice <a href=\"https:\/\/www.propertycasualty360.com\/2019\/09\/05\/four-digital-transformation-successes-in-insurance\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gustavo G\u00f3mez<\/a>, fundador y CEO de Bizagi. Para innovar, las compa\u00f1\u00edas de seguros necesitar\u00e1n empleados con conocimientos digitales con un profundo conocimiento de las oportunidades y desaf\u00edos que brindan las nuevas tecnolog\u00edas.  <\/p>\n\n<h2 class=\"wp-block-heading\">El panorama cambiante de la distribuci\u00f3n de productos<\/h2>\n\n<p class=\"wp-block-paragraph\">Pocos aspectos de los seguros han quedado sin cambios por la revoluci\u00f3n digital. Sin embargo, la distribuci\u00f3n de productos ser\u00e1 un \u00e1rea que experimentar\u00e1 algunos de los mayores cambios en la pr\u00f3xima d\u00e9cada. <\/p>\n\n<p class=\"wp-block-paragraph\">Poder distribuir productos a trav\u00e9s de nuevos canales y poder agrupar una variedad de productos que una aseguradora normalmente no suscribir\u00eda ser\u00e1 una revelaci\u00f3n para las aseguradoras establecidas.<\/p>\n\n<p class=\"wp-block-paragraph\">Con tantas opciones de transformaci\u00f3n en juego, tal vez no sea sorprendente que el 90 por ciento de los ejecutivos de seguros tengan un plan coherente a largo plazo para la innovaci\u00f3n tecnol\u00f3gica en sus negocios.<\/p>\n\n<p class=\"wp-block-paragraph\">Muchos l\u00edderes de seguros expresan entusiasmo por los beneficios potenciales de la nueva tecnolog\u00eda. \u00abLas eficiencias operativas que puede capturar aplicando tecnolog\u00eda al middle y back office son un beneficio enorme y medible en tiempo real\u00bb, dice <a href=\"https:\/\/www.accenture.com\/us-en\/insights\/financial-services\/digital-transformation-remaking-insurance\" target=\"_blank\" rel=\"noreferrer noopener\">Greg Baxter<\/a>, director digital de MetLife. <\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, no todos estos planes se centran o incluso consideran el papel que los empleados de las compa\u00f1\u00edas de seguros deber\u00e1n desempe\u00f1ar en la innovaci\u00f3n y transformaci\u00f3n digital. Al final, las tecnolog\u00edas digitales son meras herramientas. La forma en que su personal comprenda y use esas herramientas determinar\u00e1 c\u00f3mo la transformaci\u00f3n digital impulsa el crecimiento de la empresa.  <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion-1024x683.jpg\" alt=\"\" class=\"wp-image-6671\" srcset=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion-1024x683.jpg 1024w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion-300x200.jpg 300w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion-768x512.jpg 768w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion-1536x1024.jpg 1536w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/employees-discussion.jpg 1999w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 habilidades digitales necesitan los empleados?<\/h2>\n\n<p class=\"wp-block-paragraph\">Actualmente existe una brecha de habilidades digitales en todas las industrias. En un <a href=\"https:\/\/www.capgemini.com\/resources\/digital-talent-gap\/\" target=\"_blank\" rel=\"noreferrer noopener\">estudio<\/a> conjunto de CapGemini y LinkedIn, el 54 por ciento de las empresas dijo que la brecha de talento digital estaba ralentizando sus planes de transformaci\u00f3n digital, lo que les costaba a sus empresas parte o la totalidad de su ventaja competitiva. <\/p>\n\n<p class=\"wp-block-paragraph\">La brecha de habilidades digitales surgi\u00f3 de dos causas principales: la transformaci\u00f3n de las empresas en entornos digitales y la incapacidad de extraer procesos comerciales del software y el hardware, dice <a href=\"https:\/\/www.progressivepolicy.org\/wp-content\/uploads\/2019\/03\/SkillsGapFinal.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ryan Craig<\/a> del Progressive Policy Institute.<\/p>\n\n<p class=\"wp-block-paragraph\">Para tener \u00e9xito en un entorno de seguros que cambia r\u00e1pidamente, los empleados necesitan una serie de habilidades digitales.<\/p>\n\n<p class=\"wp-block-paragraph\">Las habilidades digitales fundamentales son necesarias para trabajar en un entorno digital. Incluyen la capacidad de usar hardware y software inform\u00e1tico, realizar tareas en un entorno digital y acceder a informaci\u00f3n o tutoriales, dicen <a href=\"https:\/\/www.urban.org\/sites\/default\/files\/publication\/100843\/foundational_digital_skills_for_career_progress_2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Ian Hecker y Pamela Loprest<\/a> en un estudio del Urban Institute de 2019. <\/p>\n\n<p class=\"wp-block-paragraph\">Actualmente, el 78 por ciento de los trabajos de habilidades medias requieren habilidades digitales fundamentales. Estos trabajos incluyen una amplia gama de puestos en seguros. Garantizar que el personal tenga una base s\u00f3lida en estas habilidades ayuda a los trabajadores a responder de manera m\u00e1s flexible a los cambios en la tecnolog\u00eda. Estas habilidades tambi\u00e9n ayudan a los empleados con conocimientos digitales a utilizar herramientas para innovar y comprometerse m\u00e1s plenamente con un mundo de seguros cambiante.   <\/p>\n\n<p class=\"wp-block-paragraph\">Un estudio de LinkedIn de 2019 identific\u00f3 la computaci\u00f3n en la nube como la habilidad digital m\u00e1s demandada, dice <a href=\"https:\/\/www.cnbc.com\/2019\/01\/08\/the-25-most-in-demand-technical-skills-of-2019-according-to-linkedin-.html\" target=\"_blank\" rel=\"noreferrer noopener\">Abigail Hess<\/a>, reportera de CNBC. Actualmente, la computaci\u00f3n en la nube revolucionar\u00e1 los seguros de varias maneras, desde la eliminaci\u00f3n de los silos de las propias aseguradoras hasta el posicionamiento de la cobertura de seguros de manera personalizada. Los ecosistemas de seguros tambi\u00e9n dependen de la computaci\u00f3n en la nube para compartir informaci\u00f3n y conocer a los clientes en los momentos precisos de sus vidas en los que requieren cobertura.  <\/p>\n\n<p class=\"wp-block-paragraph\">Si bien muchos trabajadores est\u00e1n familiarizados con el uso de software que opera en un entorno de nube, menos entienden la tecnolog\u00eda detr\u00e1s de la computaci\u00f3n en la nube. Cuando los profesionales de seguros entienden c\u00f3mo funciona la computaci\u00f3n en la nube, est\u00e1n mejor equipados para innovar con la tecnolog\u00eda disponible. Tambi\u00e9n pueden abordar mejor los riesgos de seguridad que vienen con los entornos en la nube.  <\/p>\n\n<p class=\"wp-block-paragraph\">La IA revolucionar\u00e1 el mundo digital, pero la mayor\u00eda de los profesionales de seguros no tienen las habilidades o la educaci\u00f3n para implementarla.<\/p>\n\n<p class=\"wp-block-paragraph\">\u00abLa cantidad de personas que realmente pueden desarrollar habilidades de IA y modelos de IA es peque\u00f1a, por lo que estamos a punto de ver un problema realmente exacerbado en t\u00e9rminos de talento y desarrollo\u00bb, dice <a href=\"https:\/\/films.economist.com\/winningedge\/building_a_winning_workforce_for_the_digital_age?linkId=100000004506692\" target=\"_blank\" rel=\"noreferrer noopener\">Dan Hushon<\/a>, vicepresidente senior y CTO de DXC Technology.<\/p>\n\n<p class=\"wp-block-paragraph\">Hushon se\u00f1ala que muchos trabajadores tienen las habilidades necesarias para usar software con IA integrada, como chatbots y herramientas anal\u00edticas. Lo que les falta a estos trabajadores es la capacidad de comprender el papel de la IA en el software. Como resultado, se ven obstaculizados en su capacidad para solucionar problemas de IA o para encontrar formas innovadoras de implementarla.  <\/p>\n\n<p class=\"wp-block-paragraph\">Desarrollar las habilidades digitales de los empleados de seguros tambi\u00e9n puede ayudar a las aseguradoras a proteger su propio crecimiento futuro a largo plazo. Las habilidades digitales son clave para el liderazgo en el futuro, as\u00ed como para la capacidad de los empleados para contribuir e innovar en cada puesto que ocupan a lo largo de su carrera, dicen <a href=\"https:\/\/www2.deloitte.com\/content\/dam\/Deloitte\/ie\/Documents\/FinancialServices\/IE_FS_talentinInsurance_0918_FINAL3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Valarie Daunt, Donal Lehane y Dawn Keaney<\/a> en Deloitte. <\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration-1024x683.jpg\" alt=\"\" class=\"wp-image-6681\" srcset=\"https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration-1024x683.jpg 1024w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration-300x200.jpg 300w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration-768x512.jpg 768w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration-1536x1024.jpg 1536w, https:\/\/bolttech.io\/wp-content\/uploads\/2024\/08\/team-collaboration.jpg 1999w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<h2 class=\"wp-block-heading\">Mejores pr\u00e1cticas para crear un equipo con conocimientos digitales<\/h2>\n\n<p class=\"wp-block-paragraph\">Los trabajadores quieren nuevas habilidades digitales. Un estudio de PwC realizado por <a href=\"https:\/\/www.pwc.com\/us\/en\/services\/consulting\/library\/consumer-intelligence-series\/tech-at-work.html\" target=\"_blank\" rel=\"noreferrer noopener\">Carrie Duarte, Dan Staley y Bhushan Sethi<\/a> encontr\u00f3 que los trabajadores estadounidenses est\u00e1n dispuestos a dedicar 15 horas al mes en promedio para aprender nuevas habilidades tecnol\u00f3gicas. <\/p>\n\n<p class=\"wp-block-paragraph\">Sin embargo, el estudio tambi\u00e9n revel\u00f3 algunos obst\u00e1culos para este impulso por la educaci\u00f3n. Si bien la mayor\u00eda de los empleados quer\u00edan aprender nuevas habilidades, solo el 50 por ciento estaba satisfecho con los recursos disponibles para mejorar sus habilidades, y el 46 por ciento dijo que su empleador no reconocer\u00eda ni recompensar\u00eda sus esfuerzos para aprender nuevas habilidades de todos modos. <\/p>\n\n<p class=\"wp-block-paragraph\">Para construir un equipo de empleados con conocimientos digitales, los empleadores deben darse cuenta de que la experiencia del empleado y las tecnolog\u00edas digitales ya no son categor\u00edas separadas, dice <a href=\"https:\/\/www.forbes.com\/sites\/joemckendrick\/2018\/11\/21\/what-do-employees-want-they-want-digital-skills\/#29c69fb47f56\" target=\"_blank\" rel=\"noreferrer noopener\">Joe McKendrick<\/a> de Forbes. M\u00e1s bien, uno influye en el otro. <\/p>\n\n<p class=\"wp-block-paragraph\">El estudio de PwC encontr\u00f3 una brecha significativa entre las opiniones de los l\u00edderes y los trabajadores sobre las tecnolog\u00edas reci\u00e9n instituidas. Por ejemplo, mientras que el 90 por ciento de los ejecutivos de C-suite dijeron que consideraban la interacci\u00f3n humana al elegir nuevas tecnolog\u00edas, solo el 53 por ciento de su personal estuvo de acuerdo. <\/p>\n\n<p class=\"wp-block-paragraph\">Para mejorar las decisiones tecnol\u00f3gicas, impulse la participaci\u00f3n de los empleados desde el principio, dicen Duarte, Staley y Sethi. \u00abElija personas de una variedad de niveles y departamentos en toda la empresa para desempe\u00f1ar roles en la planificaci\u00f3n, selecci\u00f3n y dise\u00f1o de herramientas tecnol\u00f3gicas\u00bb. <\/p>\n\n<p class=\"wp-block-paragraph\">Un sistema regular de recopilaci\u00f3n de comentarios a lo largo del proceso de implementaci\u00f3n garantiza que el personal comprenda las nuevas tecnolog\u00edas. Tambi\u00e9n puede ofrecer recomendaciones adaptadas a sus roles espec\u00edficos, lo que aumenta la productividad y el compromiso. <\/p>\n\n<p class=\"wp-block-paragraph\">Los trabajadores de hoy, particularmente los de las cohortes Millennial y Gen Z, saben lo r\u00e1pido que las habilidades digitales se vuelven obsoletas. Una encuesta de <a href=\"https:\/\/blog.edx.org\/edx-survey-finds-1-3-americans-ages-25-44-completely-changed-fields-since-starting-first-job-post-college\/?track=blog\" target=\"_blank\" rel=\"noreferrer noopener\">edX<\/a> encontr\u00f3 que solo el 20 por ciento de los graduados universitarios cre\u00edan que su educaci\u00f3n universitaria se traduc\u00eda directamente en el campo elegido. <\/p>\n\n<p class=\"wp-block-paragraph\">Un lugar para centrarse es en las habilidades de bloques de construcci\u00f3n digitales, dice <a href=\"https:\/\/www.forbes.com\/sites\/anantagarwal\/2019\/03\/13\/three-skillsets-every-employee-needs-in-2019s-digital-economy\/#5c67c7630215\" target=\"_blank\" rel=\"noreferrer noopener\">Anant Agarwal<\/a>, CEO de edX. Estas habilidades incluyen pensamiento computacional, ciencia de datos y aprendizaje autom\u00e1tico. Los empleados con conocimientos digitales tienen la capacidad no solo de comprender los sistemas y plataformas actuales en uso, sino tambi\u00e9n de comprender por qu\u00e9 estas herramientas son efectivas, c\u00f3mo hacerlas m\u00e1s efectivas y c\u00f3mo tomar decisiones informadas sobre reemplazos cuando y si es necesaria una actualizaci\u00f3n.  <\/p>\n\n<p class=\"wp-block-paragraph\">Al centrarse en las habilidades de construcci\u00f3n digital en lugar de la capacitaci\u00f3n espec\u00edfica de la plataforma, las compa\u00f1\u00edas de seguros pueden alentar a los aprendices a pensar en el c\u00f3mo y el por qu\u00e9 detr\u00e1s de las herramientas que utilizan.<\/p>\n\n<p class=\"wp-block-paragraph\">Al dar a los nuevos empleados un conjunto de habilidades escalables, las aseguradoras evitan el problema de capacitar a los empleados en una habilidad que se volver\u00e1 obsoleta.<\/p>\n\n<p class=\"wp-block-paragraph\"><em>Im\u00e1genes de: primagefactory\/\u00a9123RF.com, nd3000\/\u00a9123RF.com, Aleksandr Davydov\/\u00a9123RF.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La transformaci\u00f3n digital est\u00e1 arrasando con los seguros. Los nuevos m\u00e9todos para garantizar la seguridad, el procesamiento m\u00e1s r\u00e1pido de los reclamos, la personalizaci\u00f3n de las ofertas de seguros y una mayor transparencia han sido el resultado de un movimiento hacia un futuro digital. Las tecnolog\u00edas y plataformas digitales brindan nuevas oportunidades para la innovaci\u00f3n [&hellip;]<\/p>\n","protected":false},"featured_media":44584,"template":"","insight-category":[],"class_list":["post-44583","insight","type-insight","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/insight\/44583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/insight"}],"about":[{"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/types\/insight"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/media\/44584"}],"wp:attachment":[{"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/media?parent=44583"}],"wp:term":[{"taxonomy":"insight-category","embeddable":true,"href":"https:\/\/bolttech.io\/es\/wp-json\/wp\/v2\/insight-category?post=44583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}